{"id":1948,"date":"2017-12-04T18:18:43","date_gmt":"2017-12-04T17:18:43","guid":{"rendered":"https:\/\/www.istud.it\/imprese\/?page_id=1948"},"modified":"2021-04-09T19:01:25","modified_gmt":"2021-04-09T17:01:25","slug":"soluzioni-in-house","status":"publish","type":"page","link":"https:\/\/www.istud.it\/imprese\/soluzioni-in-house\/","title":{"rendered":"Soluzioni in house"},"content":{"rendered":"<p>[vc_row el_id=&#8221;progetti&#8221;][vc_column]<div class=\"thim-widget-heading template-base\"><div class=\"sc_heading  text-center\"><h3 style=\"text-transform: uppercase;color:#333333;\" class=\"title\">SOLUZIONI IN HOUSE<\/h3><\/div><\/div>[vc_column_text]ISTUD offre alle organizzazioni un supporto al cambiamento con interventi innovativi costruiti su misura.<\/p>\n<p>Nella progettazione dei nostri interventi applichiamo l\u2019approccio e i metodi del <strong>Design Thinking<\/strong>, partendo dal cliente e dai suoi bisogni e proponendo sempre soluzioni che tengano in considerazione i tratti competitivi e i vincoli dell\u2019impresa in cui lavoriamo. Aiutiamo le organizzazioni a liberare le proprie potenzialit\u00e0 facendo crescere le loro persone in linea con il contesto di mercato e organizzativo in cui lavorano.<\/p>\n<p>Tutte le soluzioni sono pensate per essere potenziate dalle <strong>tecnologie digitali<\/strong>, che permettono di accompagnare il partecipante per tutto il suo percorso di apprendimento, fin dalla prima fase di engagement, e per fare dell\u2019aula il momento del confronto, della socializzazione e dell\u2019apprendimento applicato.[\/vc_column_text][vc_column_text]<\/p>\n<h3>Proposte e aree di intervento<\/h3>\n<p>[\/vc_column_text][vc_row_inner equal_height=&#8221;yes&#8221; content_placement=&#8221;middle&#8221; gap=&#8221;10&#8243; css=&#8221;.vc_custom_1516650435457{margin-bottom: 0px !important;}&#8221; el_class=&#8221;centered&#8221;][vc_column_inner el_class=&#8221;white&#8221; width=&#8221;1\/3&#8243; css=&#8221;.vc_custom_1510052709916{background-color: #194a8f !important;}&#8221;][vc_column_text]<a href=\"https:\/\/www.istud.it\/imprese\/soluzioni-in-house\/aware\/\"><strong>AWARE<\/strong><\/a>[\/vc_column_text][\/vc_column_inner][vc_column_inner el_class=&#8221;white&#8221; width=&#8221;1\/3&#8243; css=&#8221;.vc_custom_1510052858220{background-color: #194a8f !important;}&#8221;][vc_column_text]<a href=\"https:\/\/www.istud.it\/imprese\/soluzioni-in-house\/a4g-awareness-for-growth-self-assessment\/\"><strong>A4G \u2013 AWARENESS FOR GROWTH \u00a9<\/strong><\/a>[\/vc_column_text][\/vc_column_inner][vc_column_inner el_class=&#8221;white&#8221; width=&#8221;1\/3&#8243; css=&#8221;.vc_custom_1510052911852{background-color: #194a8f !important;}&#8221;][vc_column_text]<a href=\"https:\/\/www.istud.it\/imprese\/soluzioni-in-house\/smart-working\/\"><strong>SMART WORKING<\/strong><\/a>[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][vc_row_inner equal_height=&#8221;yes&#8221; content_placement=&#8221;middle&#8221; gap=&#8221;10&#8243; css=&#8221;.vc_custom_1516650435457{margin-bottom: 0px !important;}&#8221; el_class=&#8221;centered&#8221;][vc_column_inner el_class=&#8221;white&#8221; width=&#8221;1\/3&#8243; css=&#8221;.vc_custom_1510052709916{background-color: #194a8f !important;}&#8221;][vc_column_text]<a href=\"https:\/\/www.istud.it\/imprese\/soluzioni-in-house\/client-relationship-management\/\"><strong>CLIENT RELATIONSHIP MANAGEMENT<\/strong><\/a>[\/vc_column_text][\/vc_column_inner][vc_column_inner el_class=&#8221;white&#8221; width=&#8221;1\/3&#8243; css=&#8221;.vc_custom_1510052858220{background-color: #194a8f !important;}&#8221;][vc_column_text]<a href=\"https:\/\/www.istud.it\/imprese\/soluzioni-in-house\/customer-centricity-and-new-selling-approach\/\"><strong>CUSTOMER CENTRICITY &amp; NEW SELLING APPROACH<\/strong><\/a>[\/vc_column_text][\/vc_column_inner][vc_column_inner el_class=&#8221;white&#8221; width=&#8221;1\/3&#8243; css=&#8221;.vc_custom_1510052911852{background-color: #194a8f !important;}&#8221;][vc_column_text]<a href=\"https:\/\/www.istud.it\/imprese\/soluzioni-in-house\/corporate-academy\/\"><strong>CORPORATE ACADEMIES<\/strong><\/a>[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][vc_row_inner equal_height=&#8221;yes&#8221; content_placement=&#8221;middle&#8221; gap=&#8221;10&#8243; css=&#8221;.vc_custom_1516650460257{margin-bottom: 0px !important;}&#8221; el_class=&#8221;centered&#8221;][vc_column_inner el_class=&#8221;white&#8221; width=&#8221;1\/3&#8243; css=&#8221;.vc_custom_1510053017643{background-color: #194a8f !important;}&#8221;][vc_column_text]<strong><a href=\"https:\/\/www.istud.it\/imprese\/soluzioni-in-house\/valorizzare-futuro-programmi-sviluppo-talenti\/\">PROGRAMMI DI SVILUPPO PER GIOVANI TALENTI<\/a><\/strong>[\/vc_column_text][\/vc_column_inner][vc_column_inner width=&#8221;1\/3&#8243; css=&#8221;.vc_custom_1508766856877{background-color: #194a8f !important;}&#8221;][vc_column_text el_class=&#8221;white&#8221;]<a href=\"https:\/\/www.istud.it\/imprese\/soluzioni-in-house\/programmi-di-sviluppo-per-i-capi\/\"><strong>PROGRAMMI DI SVILUPPO PER I CAPI<\/strong><\/a>[\/vc_column_text][\/vc_column_inner][vc_column_inner width=&#8221;1\/3&#8243; css=&#8221;.vc_custom_1508766866261{background-color: #194a8f !important;}&#8221;][vc_column_text el_class=&#8221;white&#8221;]<a href=\"https:\/\/www.istud.it\/imprese\/soluzioni-in-house\/digital-transformation\/\"><strong>DIGITAL TRANSITION<\/strong><\/a>[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][vc_row_inner equal_height=&#8221;yes&#8221; content_placement=&#8221;middle&#8221; gap=&#8221;10&#8243; css=&#8221;.vc_custom_1516650460257{margin-bottom: 0px !important;}&#8221; el_class=&#8221;centered&#8221;][vc_column_inner el_class=&#8221;white&#8221; width=&#8221;1\/3&#8243; css=&#8221;.vc_custom_1510053017643{background-color: #194a8f !important;}&#8221;][vc_column_text]<strong><a href=\"https:\/\/www.istud.it\/imprese\/soluzioni-in-house\/project-management\/\">PROJECT MANAGEMENT<\/a><\/strong>[\/vc_column_text][\/vc_column_inner][vc_column_inner el_class=&#8221;white&#8221; width=&#8221;1\/3&#8243; css=&#8221;.vc_custom_1523864430206{background-color: #194a8f !important;}&#8221;][vc_column_text]<a href=\"https:\/\/www.istud.it\/imprese\/soluzioni-in-house\/merger-and-acquisition-integration\/\"><strong>M&amp;A INTEGRATION<\/strong><\/a>[\/vc_column_text][\/vc_column_inner][vc_column_inner el_class=&#8221;white&#8221; width=&#8221;1\/3&#8243; css=&#8221;.vc_custom_1523864435372{background-color: #194a8f !important;}&#8221;][vc_column_text]<a href=\"https:\/\/www.istud.it\/imprese\/soluzioni-in-house\/analogie\/\"><strong>ANALOGIE<\/strong><\/a>[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][vc_row_inner equal_height=&#8221;yes&#8221; content_placement=&#8221;middle&#8221; gap=&#8221;10&#8243; css=&#8221;.vc_custom_1516650460257{margin-bottom: 0px !important;}&#8221; el_class=&#8221;centered&#8221;][vc_column_inner el_class=&#8221;white&#8221; width=&#8221;1\/3&#8243; css=&#8221;.vc_custom_1510053017643{background-color: #194a8f !important;}&#8221;][vc_column_text]<strong><a href=\"https:\/\/www.istud.it\/imprese\/soluzioni-in-house\/smart-coaching\/\">SMART COACHING<\/a><\/strong>[\/vc_column_text][\/vc_column_inner][vc_column_inner el_class=&#8221;white&#8221; width=&#8221;1\/3&#8243; css=&#8221;.vc_custom_1523864430206{background-color: #194a8f !important;}&#8221;][vc_column_text]<a href=\"https:\/\/www.istud.it\/imprese\/soluzioni-in-house\/smart-team-coaching\/\"><strong>SMART TEAM COACHING<\/strong><\/a>[\/vc_column_text][\/vc_column_inner][vc_column_inner el_class=&#8221;white&#8221; width=&#8221;1\/3&#8243; css=&#8221;.vc_custom_1523864435372{background-color: #194a8f !important;}&#8221;][vc_column_text]<a href=\"https:\/\/www.istud.it\/imprese\/soluzioni-in-house\/shoot-the-future\/\"><strong>SHOOT THE FUTURE\u00a9<\/strong><\/a>[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row][vc_column][vc_column_text]<\/p>\n<h3>Il team ISTUD per lo sviluppo dei Progetti In House<\/h3>\n<p>[\/vc_column_text][vc_row_inner][vc_column_inner width=&#8221;1\/2&#8243;]<div class=\"smile_icon_list_wrap ult_info_list_container ult-adjust-bottom-margin  \"><ul class=\"smile_icon_list left circle with_bg\"><li class=\"icon_list_item\" style=\" font-size:72px;\"><div class=\"icon_list_icon\" data-animation=\"\" data-animation-delay=\"03\" style=\"font-size:24px;border-width:1px;border-style:none;background:#194a8f;color:#ffffff;border-color:#333333;\"><i class=\"Defaults-briefcase\" ><\/i><\/div><div class=\"icon_description\" id=\"Info-list-wrap-2608\" style=\"font-size:24px;\"><h3 class=\"ult-responsive\"  data-ultimate-target='#Info-list-wrap-2608 h3'  data-responsive-json-new='{\"font-size\":\"desktop:16px;\",\"line-height\":\"desktop:24px;\"}'  style=\"\">Client Leader<\/h3><div class=\"icon_description_text ult-responsive\"  data-ultimate-target='#Info-list-wrap-2608 .icon_description_text'  data-responsive-json-new='{\"font-size\":\"desktop:13px;\",\"line-height\":\"desktop:18px;\"}'  style=\"\"><p>Aiuta il Cliente a comprendere il progetto dal punto di vista metodologico, culturale, di comunicazione, di opportunit\u00e0, sviluppandone i bisogni. Garantisce e monitora la soddisfazione del Cliente durante tutto il processo e gli restituisce sistematicamente feedback.<\/p>\n<\/div><\/div><div class=\"icon_list_connector\"  style=\"border-right-width: 1px;border-right-style: dashed;border-color: #333333;\"><\/div><\/li><li class=\"icon_list_item\" style=\" font-size:72px;\"><div class=\"icon_list_icon\" data-animation=\"\" data-animation-delay=\"03\" style=\"font-size:24px;border-width:1px;border-style:none;background:#194a8f;color:#ffffff;border-color:#333333;\"><i class=\"Defaults-search\" ><\/i><\/div><div class=\"icon_description\" id=\"Info-list-wrap-8407\" style=\"font-size:24px;\"><h3 class=\"ult-responsive\"  data-ultimate-target='#Info-list-wrap-8407 h3'  data-responsive-json-new='{\"font-size\":\"desktop:16px;\",\"line-height\":\"desktop:24px;\"}'  style=\"\">Project Manager<\/h3><div class=\"icon_description_text ult-responsive\"  data-ultimate-target='#Info-list-wrap-8407 .icon_description_text'  data-responsive-json-new='{\"font-size\":\"desktop:13px;\",\"line-height\":\"desktop:18px;\"}'  style=\"\"><p>Disegna e coordina il progetto e il percorso formativo insieme al Cliente. Definisce principi, contenuti, modalit\u00e0 di realizzazione e strumenti di valutazione, in coerenza con le necessit\u00e0 del Cliente.\u00a0Coordina la faculty coinvolta nel progetto, monitorandone &#8211; insieme al Client Leader &#8211; la performance.<\/p>\n<\/div><\/div><div class=\"icon_list_connector\"  style=\"border-right-width: 1px;border-right-style: dashed;border-color: #333333;\"><\/div><\/li><li class=\"icon_list_item\" style=\" font-size:72px;\"><div class=\"icon_list_icon\" data-animation=\"\" data-animation-delay=\"03\" style=\"font-size:24px;border-width:1px;border-style:none;background:#194a8f;color:#ffffff;border-color:#333333;\"><i class=\"Defaults-user\" ><\/i><\/div><div class=\"icon_description\" id=\"Info-list-wrap-3939\" style=\"font-size:24px;\"><h3 class=\"ult-responsive\"  data-ultimate-target='#Info-list-wrap-3939 h3'  data-responsive-json-new='{\"font-size\":\"desktop:16px;\",\"line-height\":\"desktop:24px;\"}'  style=\"\">Docenti<\/h3><div class=\"icon_description_text ult-responsive\"  data-ultimate-target='#Info-list-wrap-3939 .icon_description_text'  data-responsive-json-new='{\"font-size\":\"desktop:13px;\",\"line-height\":\"desktop:18px;\"}'  style=\"\"><p>Sono responsabili della qualit\u00e0 dei metodi e dei contenuti &#8211; erogati in presenza e in ambiente digitale &#8211; e si coordinano costantemente con il Project Manager.<\/p>\n<\/div><\/div><div class=\"icon_list_connector\"  style=\"border-right-width: 1px;border-right-style: dashed;border-color: #333333;\"><\/div><\/li><\/ul><\/div>[\/vc_column_inner][vc_column_inner width=&#8221;1\/2&#8243;]<div class=\"smile_icon_list_wrap ult_info_list_container ult-adjust-bottom-margin  \"><ul class=\"smile_icon_list left circle with_bg\"><li class=\"icon_list_item\" style=\" font-size:72px;\"><div class=\"icon_list_icon\" data-animation=\"\" data-animation-delay=\"03\" style=\"font-size:24px;border-width:1px;border-style:none;background:#194a8f;color:#ffffff;border-color:#333333;\"><i class=\"Defaults-comments\" ><\/i><\/div><div class=\"icon_description\" id=\"Info-list-wrap-2972\" style=\"font-size:24px;\"><h3 class=\"ult-responsive\"  data-ultimate-target='#Info-list-wrap-2972 h3'  data-responsive-json-new='{\"font-size\":\"desktop:16px;\",\"line-height\":\"desktop:24px;\"}'  style=\"\">Coach<\/h3><div class=\"icon_description_text ult-responsive\"  data-ultimate-target='#Info-list-wrap-2972 .icon_description_text'  data-responsive-json-new='{\"font-size\":\"desktop:13px;\",\"line-height\":\"desktop:18px;\"}'  style=\"\"><p>Segue il singolo partecipante o il team di progetto attraverso sessioni dedicate di coaching durante lo svolgimento del percorso.<\/p>\n<\/div><\/div><div class=\"icon_list_connector\"  style=\"border-right-width: 1px;border-right-style: dashed;border-color: #333333;\"><\/div><\/li><li class=\"icon_list_item\" style=\" font-size:72px;\"><div class=\"icon_list_icon\" data-animation=\"\" data-animation-delay=\"03\" style=\"font-size:24px;border-width:1px;border-style:none;background:#194a8f;color:#ffffff;border-color:#333333;\"><i class=\"Defaults-clipboard paste\" ><\/i><\/div><div class=\"icon_description\" id=\"Info-list-wrap-7115\" style=\"font-size:24px;\"><h3 class=\"ult-responsive\"  data-ultimate-target='#Info-list-wrap-7115 h3'  data-responsive-json-new='{\"font-size\":\"desktop:16px;\",\"line-height\":\"desktop:24px;\"}'  style=\"\">Staff organizzativo e amministrativo<\/h3><div class=\"icon_description_text ult-responsive\"  data-ultimate-target='#Info-list-wrap-7115 .icon_description_text'  data-responsive-json-new='{\"font-size\":\"desktop:13px;\",\"line-height\":\"desktop:18px;\"}'  style=\"\"><p>Seguono la pianificazione delle attivit\u00e0 e la gestione organizzativa, logistica ed economico-finanziaria del progetto, anche con riferimento all&#8217;impiego dei Fondi Interprofessionali.<\/p>\n<\/div><\/div><div class=\"icon_list_connector\"  style=\"border-right-width: 1px;border-right-style: dashed;border-color: #333333;\"><\/div><\/li><\/ul><\/div>[\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row full_width=&#8221;stretch_row&#8221; css=&#8221;.vc_custom_1519653688541{margin-bottom: -100px !important;background-color: #194a8f !important;}&#8221; el_id=&#8221;contattaci&#8221;][vc_column width=&#8221;1\/6&#8243;][\/vc_column][vc_column width=&#8221;2\/3&#8243; el_class=&#8221;centered&#8221;]<div class=\"thim-widget-heading template-base\"><div class=\"sc_heading  text-center\"><h3 style=\"text-transform: uppercase;color:#ffffff;\" class=\"title\">Contattaci per maggiori informazioni<\/h3><\/div><\/div><div role=\"form\" class=\"wpcf7\" id=\"wpcf7-f71-o1\" lang=\"it-IT\" dir=\"ltr\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/imprese\/wp-json\/wp\/v2\/pages\/1948#wpcf7-f71-o1\" method=\"post\" class=\"wpcf7-form init\" novalidate=\"novalidate\" data-status=\"init\">\n<div style=\"display: none;\">\n<input type=\"hidden\" name=\"_wpcf7\" value=\"71\" \/>\n<input type=\"hidden\" name=\"_wpcf7_version\" value=\"5.5.6\" \/>\n<input type=\"hidden\" name=\"_wpcf7_locale\" value=\"it_IT\" \/>\n<input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f71-o1\" \/>\n<input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/>\n<input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/>\n<input type=\"hidden\" name=\"_wpcf7_recaptcha_response\" value=\"\" \/>\n<\/div>\n<p><span class=\"wpcf7-form-control-wrap your-name\"><input type=\"text\" name=\"your-name\" value=\"\" size=\"40\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Nome *\" \/><\/span> <\/p>\n<p><span class=\"wpcf7-form-control-wrap your-email\"><input type=\"email\" name=\"your-email\" value=\"\" size=\"40\" class=\"wpcf7-form-control wpcf7-text wpcf7-email wpcf7-validates-as-required wpcf7-validates-as-email\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Email *\" \/><\/span> <\/p>\n<p><span class=\"wpcf7-form-control-wrap your-subject\"><input type=\"text\" name=\"your-subject\" value=\"\" size=\"40\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Oggetto *\" \/><\/span> <\/p>\n<p><span class=\"wpcf7-form-control-wrap your-message\"><textarea name=\"your-message\" cols=\"40\" rows=\"10\" class=\"wpcf7-form-control wpcf7-textarea wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Messaggio *\"><\/textarea><\/span> <\/p>\n<p align=\"left\"><font color=\"#ffffff\"><strong>Privacy*<\/strong><br \/>Ho letto l'<a href=\"https:\/\/www.istud.it\/privacy-informativa-e-richiesta-di-consenso-form\/\" target=\"_blank\" style=\"color:#ffffff; text-decoration: underline\"><strong>informativa<\/strong><\/a> e per quanto riguarda i trattamenti richiesti per consentire al Titolare del trattamento di realizzare la finalit\u00e0 di \u201cAttivit\u00e0 di Marketing\u201d (<em>informazioni pubblicitarie e promozionali, comunicazioni commerciali, newsletter e pubblicazioni periodiche, etc...<\/em>) mediante l\u2019impiego della posta cartacea, del telefono, del suo indirizzo di posta elettronica <span class=\"wpcf7-form-control-wrap privacy\"><span class=\"wpcf7-form-control wpcf7-checkbox wpcf7-validates-as-required wpcf7-exclusive-checkbox\"><span class=\"wpcf7-list-item first\"><input type=\"checkbox\" name=\"privacy\" value=\"Accetto\" \/><span class=\"wpcf7-list-item-label\">Accetto<\/span><\/span><span class=\"wpcf7-list-item last\"><input type=\"checkbox\" name=\"privacy\" value=\"Non accetto\" \/><span class=\"wpcf7-list-item-label\">Non accetto<\/span><\/span><\/span><\/span><\/font><\/p>\n<p><input type=\"submit\" value=\"Invia\" class=\"wpcf7-form-control has-spinner wpcf7-submit\" \/><\/p>\n<div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div><\/form><\/div>[\/vc_column][vc_column width=&#8221;1\/6&#8243;][\/vc_column][\/vc_row]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>[vc_row el_id=&#8221;progetti&#8221;][vc_column][vc_column_text]ISTUD offre alle organizzazioni un supporto al cambiamento con interventi innovativi costruiti su misura. Nella progettazione dei nostri interventi applichiamo l\u2019approccio e i metodi del Design Thinking, partendo dal &hellip; <\/p>\n","protected":false},"author":89,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"categories":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v18.4.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Soluzioni in house - ISTUD Imprese<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.istud.it\/imprese\/soluzioni-in-house\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Soluzioni in house - ISTUD Imprese\" \/>\n<meta property=\"og:description\" content=\"[vc_row el_id=&#8221;progetti&#8221;][vc_column][vc_column_text]ISTUD offre alle organizzazioni un supporto al cambiamento con interventi innovativi costruiti su misura. Nella progettazione dei nostri interventi applichiamo l\u2019approccio e i metodi del Design Thinking, partendo dal &hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.istud.it\/imprese\/soluzioni-in-house\/\" \/>\n<meta property=\"og:site_name\" content=\"ISTUD Imprese\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/fondazioneistud\/\" \/>\n<meta property=\"article:modified_time\" content=\"2021-04-09T17:01:25+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary\" \/>\n<meta name=\"twitter:site\" content=\"@istud_it\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"5 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.istud.it\/imprese\/#website\",\"url\":\"https:\/\/www.istud.it\/imprese\/\",\"name\":\"ISTUD Imprese\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.istud.it\/imprese\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.istud.it\/imprese\/soluzioni-in-house\/#webpage\",\"url\":\"https:\/\/www.istud.it\/imprese\/soluzioni-in-house\/\",\"name\":\"Soluzioni in house - ISTUD Imprese\",\"isPartOf\":{\"@id\":\"https:\/\/www.istud.it\/imprese\/#website\"},\"datePublished\":\"2017-12-04T17:18:43+00:00\",\"dateModified\":\"2021-04-09T17:01:25+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.istud.it\/imprese\/soluzioni-in-house\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.istud.it\/imprese\/soluzioni-in-house\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.istud.it\/imprese\/soluzioni-in-house\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.istud.it\/imprese\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Soluzioni in house\"}]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Soluzioni in house - ISTUD Imprese","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.istud.it\/imprese\/soluzioni-in-house\/","og_locale":"it_IT","og_type":"article","og_title":"Soluzioni in house - ISTUD Imprese","og_description":"[vc_row el_id=&#8221;progetti&#8221;][vc_column][vc_column_text]ISTUD offre alle organizzazioni un supporto al cambiamento con interventi innovativi costruiti su misura. Nella progettazione dei nostri interventi applichiamo l\u2019approccio e i metodi del Design Thinking, partendo dal &hellip;","og_url":"https:\/\/www.istud.it\/imprese\/soluzioni-in-house\/","og_site_name":"ISTUD Imprese","article_publisher":"https:\/\/www.facebook.com\/fondazioneistud\/","article_modified_time":"2021-04-09T17:01:25+00:00","twitter_card":"summary","twitter_site":"@istud_it","twitter_misc":{"Tempo di lettura stimato":"5 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"https:\/\/www.istud.it\/imprese\/#website","url":"https:\/\/www.istud.it\/imprese\/","name":"ISTUD Imprese","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.istud.it\/imprese\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.istud.it\/imprese\/soluzioni-in-house\/#webpage","url":"https:\/\/www.istud.it\/imprese\/soluzioni-in-house\/","name":"Soluzioni in house - ISTUD Imprese","isPartOf":{"@id":"https:\/\/www.istud.it\/imprese\/#website"},"datePublished":"2017-12-04T17:18:43+00:00","dateModified":"2021-04-09T17:01:25+00:00","breadcrumb":{"@id":"https:\/\/www.istud.it\/imprese\/soluzioni-in-house\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.istud.it\/imprese\/soluzioni-in-house\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.istud.it\/imprese\/soluzioni-in-house\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.istud.it\/imprese\/"},{"@type":"ListItem","position":2,"name":"Soluzioni in house"}]}]}},"_links":{"self":[{"href":"https:\/\/www.istud.it\/imprese\/wp-json\/wp\/v2\/pages\/1948"}],"collection":[{"href":"https:\/\/www.istud.it\/imprese\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.istud.it\/imprese\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.istud.it\/imprese\/wp-json\/wp\/v2\/users\/89"}],"replies":[{"embeddable":true,"href":"https:\/\/www.istud.it\/imprese\/wp-json\/wp\/v2\/comments?post=1948"}],"version-history":[{"count":44,"href":"https:\/\/www.istud.it\/imprese\/wp-json\/wp\/v2\/pages\/1948\/revisions"}],"predecessor-version":[{"id":10780,"href":"https:\/\/www.istud.it\/imprese\/wp-json\/wp\/v2\/pages\/1948\/revisions\/10780"}],"wp:attachment":[{"href":"https:\/\/www.istud.it\/imprese\/wp-json\/wp\/v2\/media?parent=1948"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.istud.it\/imprese\/wp-json\/wp\/v2\/categories?post=1948"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}